{"id":3494,"date":"2022-10-11T16:13:33","date_gmt":"2022-10-11T16:13:33","guid":{"rendered":"https:\/\/iqra-quran.com\/unkategorisiert\/surah-ali-imran-3-hauptthemen-und-analyse-der-rukus\/"},"modified":"2025-01-06T15:15:32","modified_gmt":"2025-01-06T15:15:32","slug":"3-ali-imran","status":"publish","type":"post","link":"https:\/\/iqra-quran.com\/de\/kapitel-des-korans\/3-ali-imran\/","title":{"rendered":"Surah Ali &#8218;Imran [3] | \u00dcberblick, Themen, Lektionen &amp; Mehr"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3494\" class=\"elementor elementor-3494 elementor-1158\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfed478 e-flex e-con-boxed e-con e-parent\" data-id=\"bfed478\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0dbb70f e-flex e-con-boxed e-con e-child\" data-id=\"0dbb70f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d55b763 elementor-widget elementor-widget-text-editor\" data-id=\"d55b763\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Name der Sure:<\/strong> Ali-Imran (\u0633\u0648\u0631\u0629 \u0622\u0644 \u0639\u0645\u0631\u0627\u0646)<br \/><strong>\u00dcbersetzung:<\/strong> Die Familie Imrans<br \/><strong>Ursprung des Namens:<\/strong> Diese Sure tr\u00e4gt ihren Namen aus Vers 33, in dem Imran erw\u00e4hnt wird. Laut Quellen werden zwei verschiedene Personen namens Imran erw\u00e4hnt: einer ist der Vater von Moses und Aaron, und der andere ist der Vater von Maria. W\u00e4hrend es einige Diskussionen dar\u00fcber gibt, welcher Imran hier gemeint ist, deuten die folgenden Verse, insbesondere diejenigen, die sich mit Marias Keuschheit und der Prophetenschaft Jesu befassen, darauf hin, dass der gemeinte Imran Marias Vater ist.<\/p>\n<p><strong>Nummer der Sure:<\/strong> 3<br \/><strong>Anzahl der Ayahs (Verse):<\/strong> 200  <\/p>\n<p><strong>Makki oder Madani:<\/strong> Madani<br \/><strong>Ungef\u00e4hre Zeit der Offenbarung:<\/strong> Die Sure wurde in mehreren Phasen offenbart, mit Teilen, die kurz nach der Schlacht von Badr (im Jahr 2-3 nach der Hijrah) offenbart wurden, w\u00e4hrend des Besuchs der Christen aus Najran im Jahr 9 nach der Hijrah und nach der Schlacht von Uhud (im Jahr 3-4 nach der Hijrah). Die vollst\u00e4ndige Offenbarung fand wahrscheinlich zwischen dem 3. und 9. Jahr nach der Hijrah statt.<\/p>\n<h2 id=\"historischer-kontext\">Historischer Kontext<\/h2>\n<p>Die Sure Al-Imran wurde \u00fcber mehrere Jahre in Madinah offenbart und behandelt Ereignisse w\u00e4hrend der Phase der fr\u00fchen Muslime<\/p>\n<p>Zu dieser Zeit waren die Muslime externen Bedrohungen wie die Quraysh aus Makkah und internen Herausforderungen durch die j\u00fcdischen St\u00e4mme und Heuchler in Madinah ausgesetzt. Die Auswirkungen der beiden bedeutenden Schlachten \u2013 der Schlacht von Badr, einem Sieg, und der Schlacht von Uhud, in der die Muslime eine Niederlage erlitten \u2013 werden in der Sure direkt angesprochen. Beide Schlachten beeinflussten die Muslime und boten neue Lektionen, die einer Reflexion bedurften.<\/p>\n<p>Au\u00dferdem bietet der Besuch einer christlichen Delegation aus Najran in Madinah einen wichtigen Kontext f\u00fcr Teile der Sure, die gemeinsame theologische Themen zwischen Islam und Christentum, insbesondere die Gestalt von Jesus (Isa), ansprechen. Die Botschaft an die Christen stimmt mit den im Koran bewahrten Lehren \u00fcberein, kl\u00e4rt falsche \u00dcberzeugungen, die sie hatten, und l\u00e4dt sie zur\u00fcck zum wahren abrahamitischen Glauben ein.<\/p>\n<p>Die j\u00fcdischen St\u00e4mme in Madinah begannen, insbesondere nach der Schlacht von Badr, ihre B\u00fcndnisse mit den Muslimen zu brechen und ermutigten externe Feinde wie die Quraysh zum Angriff. Der Prophet Muhammad (s.a.w.) musste daher vielen Herausforderungen begegnen, sowohl von au\u00dfen als auch innerhalb seiner Gemeinschaft, da einige j\u00fcdische St\u00e4mme mit den Heuchlern und feindlichen Polytheisten konspirierten.<\/p>\n<p>Die Sure soll die Muslime beruhigen, indem sie daran erinnert, dass Geduld, Einheit und Treue entscheidend sind, um interne Schw\u00e4chen zu \u00fcberwinden, die w\u00e4hrend der Niederlage bei Uhud offengelegt wurden. Sie betont die Notwendigkeit von Gerechtigkeit und Disziplin innerhalb der Gemeinschaft, warnt vor Gier und gibt gleichzeitig umfassende Anleitungen f\u00fcr den Umgang mit den Juden und Christen.<\/p>\n<h2 id=\"hauptthemen\">Hauptthemen<\/h2>\n<ul>\n<li>\n<p><strong>Einladung an die Leute der Schrift (Juden und Christen):<\/strong><br \/>Die Sure setzt die in Al-Baqarah begonnene Einladung fort und fordert Juden und Christen auf, den Islam anzunehmen. Sie kl\u00e4rt die Wahrheit \u00fcber Prophet Jesus und widerlegt den christlichen Glauben an seine G\u00f6ttlichkeit, indem sie betont, dass Muhammad (Frieden sei mit ihm) die gleiche Botschaft bringt wie die vorherigen Propheten.<\/p>\n<\/li>\n<li>\n<p><strong>Wahrheit der Offenbarung und Monotheismus:<\/strong><br \/>Die Sure bekr\u00e4ftigt die Lehren des Monotheismus und betont, dass Allah Einer ist und alle Propheten dieselbe grundlegende Botschaft von Allah \u00fcbermittelten. Der Quran best\u00e4tigt die Wahrheit, die in fr\u00fcheren Schriften wie der Tora und dem Evangelium offenbart wurde.<\/p>\n<\/li>\n<li>\n<p><strong>Lehren aus den Schlachten von Badr und Uhud:<\/strong><br \/>Die Sure reflektiert \u00fcber die Siege und Herausforderungen der Muslime, insbesondere in den Schlachten von Badr und Uhud. Sie hebt die Bedeutung von Disziplin, Einheit und Gehorsam gegen\u00fcber Allah hervor. Die R\u00fcckschl\u00e4ge bei Uhud werden auf Gier und Ungehorsam zur\u00fcckgef\u00fchrt, was als Lehre f\u00fcr die Gemeinschaft dient.<\/p>\n<\/li>\n<li>\n<p><strong>Warnungen und Anleitung f\u00fcr Muslime:<\/strong><br \/>Muslime werden gewarnt, nicht denselben Weg des religi\u00f6sen und moralischen Verfalls einzuschlagen, den fr\u00fchere Gemeinschaften gingen. Sie werden an ihre Verantwortung erinnert, Wahrheit, Einheit und Gerechtigkeit aufrechtzuerhalten und den Quran zu bewahren.<\/p>\n<\/li>\n<li>\n<p><strong>St\u00e4rkung der muslimischen Gemeinschaft:<\/strong><br \/>Die Sure gibt Anweisungen zum Aufbau einer starken und zusammenhaltenden muslimischen Gemeinschaft. Sie behandelt den Umgang mit den Juden und Christen und warnt vor dem Einfluss von Heuchlern und Feinden des Islam.<\/p>\n<\/li>\n<li>\n<p><strong>Prophetentum und g\u00f6ttliche F\u00fchrung:<\/strong><br \/>Die Sure st\u00e4rkt das Konzept des Prophetentums, indem sie die Einheit und Kontinuit\u00e4t der prophetischen Mission von Adam bis Muhammad (Frieden sei mit ihm) erkl\u00e4rt. Die Geburt und Rolle von Jesus als Prophet wird erl\u00e4utert, wobei Missverst\u00e4ndnisse ausger\u00e4umt werden.<\/p>\n<\/li>\n<li>\n<p><strong>Gerechtigkeit und moralische St\u00e4rke:<\/strong><br \/>Die Sure betont Gerechtigkeit in allen Lebensbereichen, sei es im Umgang innerhalb der muslimischen Gemeinschaft oder mit anderen.<\/p>\n<\/li>\n<li>\n<p><strong>Aufruf zu Geduld:<\/strong><br \/>Muslime werden in der Sure ermutigt, in schwierigen Zeiten geduldig zu bleiben, auf Allah zu vertrauen und ihren Glauben an den ultimativen Erfolg derer, die sich Seinem Willen unterwerfen, zu bewahren.<\/p>\n<\/li>\n<\/ul>\n<h2 id=\"wichtige-botschaften-lehren\">Wichtige Botschaften\/Lehren<\/h2>\n<ul>\n<li>Betont den Glauben an Allahs Einheit und die konsequente Rechtleitung durch alle Propheten.<\/li>\n<li>Verurteilt das Ver\u00e4ndern g\u00f6ttlicher Lehren und warnt vor falschen Vorstellungen \u00fcber die Propheten.<\/li>\n<li>Lehrt Geduld, Aufrichtigkeit und Einheit als Wege zu Allahs Hilfe, w\u00e4hrend vor Gier und Ungehorsam gewarnt wird.<\/li>\n<li>Ruft Muslime dazu auf, \u00fcber ihre moralische Schw\u00e4chen nachzudenken und sie zu korrigieren.<\/li>\n<li>R\u00e4t zur Vorsicht gegen\u00fcber Heuchlern und Feinden; Einheit und Furcht vor Allah sch\u00fctzen vor Schaden.<\/li>\n<li>Ermutigt, den Lehren der Propheten zu folgen, ohne sie \u00fcber menschliche Rollen hinaus zu erh\u00f6hen.<\/li>\n<li>Ruft zu Geduld und Standhaftigkeit angesichts von Verleumdung oder Widerstand auf.<\/li>\n<\/ul>\n<h2 id=\"bedeutende-verse-aus-der-sure-ali-imran\">Bedeutende Verse aus der Sure Ali-Imran<\/h2>\n<ul>\n<li>\n<p><strong>Vers 19:<\/strong><br \/><em>&quot;Gewi\u00df, die Religion ist bei Allah der Islam. Doch diejenigen, denen die Schrift gegeben wurde, wurden erst uneinig, nachdem das Wissen zu ihnen gekommen war &#8211; aus Missgunst untereinander, Doch wer Allahs Zeichen verleugnet -, so ist Allah schnell im Abrechnen.&quot;<\/em><br \/>Betont, dass der Islam in den Augen Allahs die wahre Religion ist, und hebt die Spaltung unter den Schriftbesitzern (Juden &amp; Christen) aufgrund von Neid hervor.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 26:<\/strong><br \/><em>&quot;Sag: O Allah, Herr der Herrschaft, Du gibst die Herrschaft, wem Du willst, und Du entziehst die Herrschaft, wem Du willst. Du machst m\u00e4chtig, wen Du willst, und Du erniedrigst, wen Du willst. In Deiner Hand ist (all) das Gute. Gewiss, Du hast zu allem die Macht.&quot;<\/em><br \/>Ein Gebet, das Allahs absolute Kontrolle \u00fcber Macht und Ehre anerkennt.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 27:<\/strong><br \/><em>&quot;Du l\u00e4sst die Nacht in den Tag eindringen und l\u00e4sst den Tag eindringen in die Nacht. Und Du l\u00e4sst das Lebendige aus dem Toten hervorgehen und l\u00e4sst hervorgehen das Tote aus dem Lebendigen. Und Du versorgst, wen Du willst, ohne zu berechnen.&quot;<\/em><br \/>Hebt Allahs Macht \u00fcber Sch\u00f6pfung, Leben und Versorgung hervor.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 31:<\/strong><br \/><em>&quot;Sag: Wenn ihr Allah liebt, dann folgt mir. So liebt euch Allah und vergibt euch eure S\u00fcnden. Allah ist Allvergebend und Barmherzig.&quot;<\/em><br \/>Eine direkte Einladung an die Menschen, dem Propheten Muhammad (s.a.w.) zu folgen, um Allahs Liebe und Vergebung zu erlangen.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 39:<\/strong><br \/><em>&quot;Und da riefen ihm die Engel zu, w\u00e4hrend er zum Gebet in dem Tempel stand: &quot;Siehe, Allah verhei\u00dft dir Johannes, den Best\u00e4tiger eines Wortes von Allah, einen Vornehmen, einen Asketen und Propheten, einen von den Rechtschaffenen.&quot;&quot;<\/em><br \/>Bezieht sich auf die wundersame Geburt von Johannes (Yahya) an Zacharias, ein wichtiger Bezugspunkt im Dialog mit Christen.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 42:<\/strong><br \/><em>&quot;Und damals sprachen die Engel: &quot;O Maria, siehe, Allah hat dich auserw\u00e4hlt und gereinigt und erw\u00e4hlt vor den Frauen der Welten.&quot;<\/em><br \/>Anerkennt den besonderen Status von Maria im Islam und weist jegliche Verleumdung gegen sie zur\u00fcck.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 59:<\/strong><br \/><em>&quot;Wahrlich, Jesus ist vor Allah gleich Adam; Er erschuf ihn aus Erde, als dann sprach Er zu ihm: &quot;Sei!&quot; und da war er.&quot;<\/em><br \/>Erkl\u00e4rt, dass ebenso wie Adam ohne Eltern erschaffen wurde, die wundersame Geburt Jesu ihn nicht g\u00f6ttlich macht.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 64:<\/strong><br \/><em>&quot;Sprich: &quot;O Volk der Schrift, kommt herbei zu einem gleichen Wort zwischen uns und euch, dass wir n\u00e4mlich Allah allein dienen und nichts neben Ihn stellen und dass nicht die einen von uns die anderen zu Herren nehmen au\u00dfer Allah.&quot; Und wenn sie sich abwenden, so sprecht: &quot;Bezeugt, dass wir (Ihm) ergeben sind.&quot;&quot;<\/em><br \/>Eine Einladung zur Einheit im Glauben und zur Verehrung des einen Gottes, gerichtet an die Schriftbesitzer.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 92:<\/strong><br \/><em>&quot;Ihr werdet das G\u00fctigsein nicht erlangen, ehe ihr nicht von dem spendet, was ihr liebt&#8230;&quot;<\/em><br \/>Ermutigung, aus dem zu spenden, was einem am liebsten ist.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 103:<\/strong><br \/><em>&quot;Und haltet insgesamt an Allahs Seil fest und zerfallet nicht&#8230;&quot;<\/em><br \/>Eine starke Aufforderung zur Wahrung der Einheit und zur Vermeidung von Spaltungen innerhalb der muslimischen Gemeinschaft.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 110:<\/strong><br \/><em>&quot;Ihr seid die beste Gemeinde, die f\u00fcr die Menschen entstand. Ihr gebietet das, was Rechtens ist, und ihr verbietet das Unrecht, und ihr glaubt an Allah&#8230;&quot;<\/em><br \/>Erkl\u00e4rt die Muslime zu der besten Gemeinschaft, die f\u00fcr die F\u00f6rderung des Guten und die Bek\u00e4mpfung des B\u00f6sen verantwortlich ist.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 144:<\/strong><br \/><em>&quot;Und Muhammad ist nur ein Gesandter; schon vor ihm gingen die Gesandten dahin. Und ob er stirbt oder get\u00f6tet wird, werdet ihr auf euren Fersen umkehren?&#8230;&quot;<\/em><br \/>Erinnert die Gemeinschaft daran, dass ihr Glaube nicht von der Anwesenheit des Propheten Muhammad, sondern von Allah abh\u00e4ngen sollte.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 159:<\/strong><br \/><em>&quot;Durch Erbarmen von Allah bist du mild zu ihnen gewesen; w\u00e4rst du aber schroff und hartherzig, so w\u00fcrden sie wahrlich rings um dich auseinanderlaufen&#8230;&quot;<\/em><br \/>Betont die Wichtigkeit von Barmherzigkeit und Freundlichkeit, insbesondere in der F\u00fchrung.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 185:<\/strong><br \/><em>&quot;Jede Seele wird den Tod kosten, und euch wird euer Lohn am Tag der Auferstehung vollst\u00e4ndig gegeben&#8230;&quot;<\/em><br \/>Eine kraftvolle Erinnerung daran, dass alle Menschen den Tod und die Rechenschaft im Jenseits erfahren werden.<\/p>\n<\/li>\n<li>\n<p><strong>Vers 200:<\/strong><br \/><em>&quot;O ihr, die ihr glaubt, \u00fcbt Geduld und wetteifert in Geduld und seid standhaft und f\u00fcrchtet Allah; vielleicht werdet ihr erfolgreich sein.&quot;<\/em><br \/>Der Abschluss der Sure, der Geduld, Ausdauer und Gottesfurcht f\u00fcr den letztendlichen Erfolg fordert.<\/p>\n<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-028623b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"028623b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfa503d elementor-widget elementor-widget-heading\" data-id=\"bfa503d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Thematische Analyse von Rukus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f27198 elementor-widget elementor-widget-heading\" data-id=\"6f27198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 1: Verse 1-9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8ef66 elementor-widget elementor-widget-text-editor\" data-id=\"4b8ef66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah stellt sich selbst vor und sagt, dass Er die drei heiligen B\u00fccher herabgesandt hat.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea8f02f elementor-widget elementor-widget-heading\" data-id=\"ea8f02f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 2: Verse 10-20<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c03b8c2 elementor-widget elementor-widget-text-editor\" data-id=\"c03b8c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah offenbart das Ende, das die Ungl\u00e4ubigen erwartet.<\/p>\n<p>Er spricht \u00fcber die Dinge, die den Menschen in dieser Welt sch\u00f6n erscheinen, und die weitaus sch\u00f6neren Dinge, die diejenigen erwarten, die glauben.<\/p>\n<p>Die Merkmale derjenigen, die Taqwa (Gottesbewusstsein) haben, wobei Allah die einzige Gottheit ist und der Islam die einzige akzeptable Religion ist.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68887d5 elementor-widget elementor-widget-heading\" data-id=\"68887d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 3: Verse 21-30<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5bbf13 elementor-widget elementor-widget-text-editor\" data-id=\"c5bbf13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah erz\u00e4hlt von den Taten und L\u00fcgen der Israeliten, die von der Wahrheit abgewichen sind.<\/p>\n<p>Allah gibt Beispiele f\u00fcr Seine eigene Macht und spricht \u00fcber den Tag des J\u00fcngsten Gerichts.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae3fdd elementor-widget elementor-widget-heading\" data-id=\"cae3fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 4: Verse 31-41<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-835a93e elementor-widget elementor-widget-text-editor\" data-id=\"835a93e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Bedeutung des Gehorsams gegen\u00fcber Allah und seinen Propheten.<\/p>\n<p>Die Beziehung von Zacharias und Maria zu Allah.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbb4f4f elementor-widget elementor-widget-heading\" data-id=\"fbb4f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 5: Verse 42-54<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e084ea elementor-widget elementor-widget-text-editor\" data-id=\"1e084ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah spricht \u00fcber die Offenbarungen, die er zu Maria (Friede sei mit ihr) herabgesandt hat, und gibt ihr die frohe Botschaft von Jesus (Friede sei mit ihm).<\/p>\n<p>Er spricht \u00fcber bestimmte Ereignisse aus dem Leben von Jesus (Friede sei mit ihm).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a98acaa elementor-widget elementor-widget-heading\" data-id=\"a98acaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 6: Verse 55-62<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c051c6a elementor-widget elementor-widget-text-editor\" data-id=\"c051c6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah spricht von dem Vorfall, bei dem Er Jesus (Friede sei mit ihm) in den Himmel aufsteigen lie\u00df, um ihn vor den Israeliten zu sch\u00fctzen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9612e9 elementor-widget elementor-widget-heading\" data-id=\"b9612e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 7: Verse 63-71<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52c8327 elementor-widget elementor-widget-text-editor\" data-id=\"52c8327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah spricht zum Volk des Buches. <\/p>\n<p>Es gibt keinen Gott au\u00dfer Allah. Die Religion Abrahams (Friede sei mit ihm). <\/p>\n<p>Allah fragt die Leute des Buches, warum sie Seine Verse leugnen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2330ff elementor-widget elementor-widget-heading\" data-id=\"c2330ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 8: Verse 72-80<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ee4079 elementor-widget elementor-widget-text-editor\" data-id=\"0ee4079\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah entlarvt die Tricks und L\u00fcgen der Heuchler unter den Leuten des Buches.<\/p>\n<p>Und Allah erkl\u00e4rt, dass weder Seine Propheten noch Seine Engel angebetet werden sollen au\u00dfer Ihm selbst.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1994561 elementor-widget elementor-widget-heading\" data-id=\"1994561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 9: Verse 81-91<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f413ba elementor-widget elementor-widget-text-editor\" data-id=\"7f413ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Verhei\u00dfung, die von den Israeliten gegeben wurde, um den kommenden Propheten zu helfen.<\/p>\n<p>Dass keine andere Religion als der Islam im Jenseits akzeptiert werden wird.<\/p>\n<p>Die Pein, die diejenigen erwartet, die absichtlich dem Unglauben verfallen sind, nachdem ihnen eindeutige Beweise von Allah gegeben wurden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13c9eed elementor-widget elementor-widget-heading\" data-id=\"13c9eed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 10: Verse 92-101<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11280d0 elementor-widget elementor-widget-text-editor\" data-id=\"11280d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah warnt die Leute des Buches, die im Namen Allahs L\u00fcgen erfinden und Seine Verse verbergen.<\/p>\n<p>Er l\u00e4dt die Menschen zur Religion Abrahams (Friede sei mit ihm) ein und gibt Informationen \u00fcber die Kaaba.<\/p>\n<p>Er befiehlt denen, die es sich leisten k\u00f6nnen, die Kaaba zu besuchen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de678f3 elementor-widget elementor-widget-heading\" data-id=\"de678f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 11: Verse 102-109<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce391c4 elementor-widget elementor-widget-text-editor\" data-id=\"ce391c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah ruft den Gl\u00e4ubigen zu, gibt ihnen Ratschl\u00e4ge und erinnert sie an seine Segnungen.<\/p>\n<p>Er beschreibt den Zustand derjenigen, die glauben, und derjenigen, die sich von ihrem Glauben abwenden, am Tag des Gerichts.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ce8666 elementor-widget elementor-widget-heading\" data-id=\"9ce8666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 12: Verse 110-120<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06f6aaf elementor-widget elementor-widget-text-editor\" data-id=\"06f6aaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah trennt Heuchler und Gl\u00e4ubige von den Leuten des Buches und z\u00e4hlt ihre Eigenschaften auf.<\/p>\n<p>Er warnt die Gl\u00e4ubigen vor den Heuchlern unter den Leuten des Buches und sagt ihnen, dass sie sie nicht zu Freunden nehmen sollen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47a9b63 elementor-widget elementor-widget-heading\" data-id=\"47a9b63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 13: Verse 121-129<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb3058b elementor-widget elementor-widget-text-editor\" data-id=\"cb3058b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah erw\u00e4hnt, dass Er den Muslimen helfen wird, die auf ihren Herrn vertrauen und geduldig sind.<\/p>\n<p>Er erz\u00e4hlt, wie er Seine Engel schickte, um den Gl\u00e4ubigen in den Schlachten von Uhud und Badr zu helfen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5ff81c elementor-widget elementor-widget-heading\" data-id=\"d5ff81c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 14: Verse 130-143<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-199c9f7 elementor-widget elementor-widget-text-editor\" data-id=\"199c9f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah erkl\u00e4rt, was die frommen Menschen getan haben und was sie vermieden haben. Er spricht auch vom Paradies, das ihre Belohnung ist.<\/p>\n<p>Er erkl\u00e4rt die Weisheit hinter Niederlagen und Siegen in Kriegen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e739be elementor-widget elementor-widget-heading\" data-id=\"8e739be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 15: Verse 144-148<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec3cc14 elementor-widget elementor-widget-text-editor\" data-id=\"ec3cc14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gott gibt den Menschen, was sie wollen, als Gegenleistung f\u00fcr das Gute, das sie tun.<\/p>\n<p>Allah sagt, dass Er diejenigen belohnt, die dankbar sind, dass Er diejenigen liebt, die geduldig sind, und diejenigen, die wohlwollend sind, und gibt Beispiele f\u00fcr diese Themen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23991fa elementor-widget elementor-widget-heading\" data-id=\"23991fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 16: Verse 149-155<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b9a5c4 elementor-widget elementor-widget-text-editor\" data-id=\"1b9a5c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah befiehlt uns, den Ungl\u00e4ubigen nicht zu folgen, und sagt, dass der Ort, der diejenigen erwartet, die neben Allah andere g\u00f6tter anbeten, die H\u00f6lle ist.<\/p>\n<p>Allah erz\u00e4hlt die Geschehnisse in der Schlacht von Uhud aus Seiner eigenen Sicht.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dae4ebb elementor-widget elementor-widget-heading\" data-id=\"dae4ebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 17: Verse 156-171<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81e99f2 elementor-widget elementor-widget-text-editor\" data-id=\"81e99f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nach der Schlacht von Uhud warnt Allah die Muslime vor den Themen Tod und Zeugenschaft;<\/p>\n<p>Der Prophet (sav) vergibt den Muslimen, die in der Schlacht von Uhud geflohen sind; er verteilt die Beute gerecht; und der Prophet (sav) ist eine Barmherzigkeit Allahs f\u00fcr alle Muslime.<\/p>\n<p>Allah spricht von den Heuchlern und M\u00e4rtyrern unter den Muslimen in der Schlacht von Uhud.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf1c0db elementor-widget elementor-widget-heading\" data-id=\"cf1c0db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 18: Verse 172-180<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f2ca28 elementor-widget elementor-widget-text-editor\" data-id=\"2f2ca28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah spricht von Gl\u00e4ubigen, die im und vor dem Krieg Heldenmut bewiesen haben.<\/p>\n<p>Er weist darauf hin, dass die Ungl\u00e4ubigen nur sich selbst schaden, nicht aber Allah.<\/p>\n<p>Allah spricht \u00fcber das Unsichtbare und den Geiz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c85c9a elementor-widget elementor-widget-heading\" data-id=\"3c85c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 19: Verse 181-189<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b3a956 elementor-widget elementor-widget-text-editor\" data-id=\"6b3a956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah spricht \u00fcber die Verhei\u00dfungen, die die Israeliten nicht eingehalten haben, \u00fcber die Propheten, die sie get\u00f6tet haben, \u00fcber ihre Verleugnung und \u00fcber die Qualen, die sie erwarten.<\/p>\n<p>Gott spricht von Pr\u00fcfungen (des Lebens) und vom Tod.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b66b99b elementor-widget elementor-widget-heading\" data-id=\"b66b99b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ruku 20: Verse 190-200<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8284374 elementor-widget elementor-widget-text-editor\" data-id=\"8284374\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allah spricht \u00fcber die Gebete der aufrichtigen Gl\u00e4ubigen, die die Beweise und Lehren Allahs sehen. Die Verhei\u00dfungen, die Er ihnen gegeben hat.<\/p>\n<p>Er spricht von frommen Menschen, die zum Volk des Buches geh\u00f6ren.<\/p>\n<p>Der Rat, den Allah den Gl\u00e4ubigen gibt.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Name der Sure: Ali-Imran (\u0633\u0648\u0631\u0629 \u0622\u0644 \u0639\u0645\u0631\u0627\u0646)\u00dcbersetzung: Die Familie ImransUrsprung des Namens: Diese Sure tr\u00e4gt ihren Namen aus Vers 33, in dem Imran erw\u00e4hnt wird. Laut Quellen werden zwei verschiedene Personen namens Imran erw\u00e4hnt: einer ist der Vater von Moses und Aaron, und der andere ist der Vater von Maria. W\u00e4hrend es einige Diskussionen dar\u00fcber [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":758,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-3494","post","type-post","status-publish","format-standard","hentry","category-kapitel-des-korans"],"_links":{"self":[{"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/posts\/3494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/comments?post=3494"}],"version-history":[{"count":3,"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/posts\/3494\/revisions"}],"predecessor-version":[{"id":3858,"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/posts\/3494\/revisions\/3858"}],"wp:attachment":[{"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/media?parent=3494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/categories?post=3494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iqra-quran.com\/de\/wp-json\/wp\/v2\/tags?post=3494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}